{"id":205339,"count":1,"description":"","link":"https:\/\/dulichdiaphuong.com\/blog\/category\/xe-bus-kon-tum\/","name":"Xe bus Kon Tum","slug":"xe-bus-kon-tum","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/categories\/205339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/posts?categories=205339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}