{"id":103880,"count":1,"description":"","link":"https:\/\/dulichdiaphuong.com\/blog\/tag\/gia-xe-du-lich-29-cho-da-lat-thanh-hoa\/","name":"gi\u00e1 xe du l\u1ecbch 29 ch\u1ed7 \u0110\u00e0 L\u1ea1t Thanh H\u00f3a","slug":"gia-xe-du-lich-29-cho-da-lat-thanh-hoa","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags\/103880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/posts?tags=103880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}