{"id":139927,"count":1,"description":"","link":"https:\/\/dulichdiaphuong.com\/blog\/tag\/binh-dinh-di-kon-tum\/","name":"B\u00ecnh \u0110\u1ecbnh \u0111i Kon Tum","slug":"binh-dinh-di-kon-tum","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags\/139927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/posts?tags=139927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}