{"id":158597,"count":1,"description":"","link":"https:\/\/dulichdiaphuong.com\/blog\/tag\/xe-quang-bac-di-tuyen-quang\/","name":"Xe Quang B\u1eafc \u0111i Tuy\u00ean Quang","slug":"xe-quang-bac-di-tuyen-quang","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags\/158597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/posts?tags=158597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}