{"id":170084,"count":1,"description":"","link":"https:\/\/dulichdiaphuong.com\/blog\/tag\/ve-xe-khach-lai-chau-da-nang\/","name":"v\u00e9 xe kh\u00e1ch Lai Ch\u00e2u \u0110\u00e0 N\u1eb5ng","slug":"ve-xe-khach-lai-chau-da-nang","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags\/170084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/posts?tags=170084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}