{"id":46564,"count":1,"description":"","link":"https:\/\/dulichdiaphuong.com\/blog\/tag\/dia-diem-du-lich-gan-chu-prong-mua-dong\/","name":"\u0111\u1ecba \u0111i\u1ec3m du l\u1ecbch g\u1ea7n Ch\u01b0 Pr\u00f4ng m\u00f9a \u0111\u00f4ng","slug":"dia-diem-du-lich-gan-chu-prong-mua-dong","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags\/46564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dulichdiaphuong.com\/blog\/wp-json\/wp\/v2\/posts?tags=46564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}